{"id":4604,"date":"2025-09-09T11:35:29","date_gmt":"2025-09-09T11:35:29","guid":{"rendered":"https:\/\/colourschalet.gr\/gallery\/"},"modified":"2025-09-17T08:18:41","modified_gmt":"2025-09-17T08:18:41","slug":"gallery","status":"publish","type":"page","link":"https:\/\/colourschalet.gr\/el\/gallery\/","title":{"rendered":"Gallery"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4604\" class=\"elementor elementor-4604 elementor-4285\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6edf5b9 e-con-full elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"6edf5b9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7baed76 elementor-widget__width-auto elementor-widget elementor-widget-oysha_core_custom_font\" data-id=\"7baed76\" data-element_type=\"widget\" data-widget_type=\"oysha_core_custom_font.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"qodef-shortcode qodef-m  qodef-custom-font qodef-custom-font-101 qodef-layout--simple qodef-align--center  \" style=\"color: #FFFFFF;font-size: 50px;line-height: 67px\" >\n\t<span class=\"qodef-e-inner\">\n\t\t\t\t\t\u03a3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03c0\u03bf\u03c5 \u03bc\u03b9\u03bb\u03bf\u03cd\u03bd \u03b1\u03c0\u03cc \u03bc\u03cc\u03bd\u03b5\u03c2 \u03c4\u03bf\u03c5\u03c2\t\t\t<\/span>\n<\/h6>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58ca9ce e-con-full elementor-hidden-desktop elementor-hidden-tablet e-flex e-con e-parent\" data-id=\"58ca9ce\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8e0eb7c elementor-widget__width-auto elementor-widget elementor-widget-oysha_core_custom_font\" data-id=\"8e0eb7c\" data-element_type=\"widget\" data-widget_type=\"oysha_core_custom_font.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h6 class=\"qodef-shortcode qodef-m  qodef-custom-font qodef-custom-font-771 qodef-layout--simple qodef-align--center  \" style=\"color: #FFFFFF;font-size: 50px;line-height: 67px\" >\n\t<span class=\"qodef-e-inner\">\n\t\t\t\t\t\u03a3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03c0\u03bf\u03c5 \u03bc\u03b9\u03bb\u03bf\u03cd\u03bd \u03b1\u03c0\u03cc \u03bc\u03cc\u03bd\u03b5\u03c2 \u03c4\u03bf\u03c5\u03c2\t\t\t<\/span>\n<\/h6>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52015d2 e-con-full e-flex e-con e-parent\" data-id=\"52015d2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89f87fa elementor-widget__width-initial elementor-widget elementor-widget-oysha_core_section_title\" data-id=\"89f87fa\" data-element_type=\"widget\" data-widget_type=\"oysha_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--center  \">\n\t\t<h3 class=\"qodef-m-title\" >\n\t\t\t\t\t\u0388\u03be\u03b9 \u03b1\u03c0\u03bf\u03c7\u03c1\u03ce\u03c3\u03b5\u03b9\u03c2 \u03ac\u03bd\u03b5\u03c3\u03b7\u03c2\t\t\t<\/h3>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bea2fb8 elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"bea2fb8\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--3 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1879\" height=\"966\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1.jpg 1879w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-300x154.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1024x526.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-768x395.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1536x790.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-600x308.jpg 600w\" sizes=\"(max-width: 1879px) 100vw, 1879px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-3.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"1020\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-3.jpg 800w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-3-235x300.jpg 235w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-3-768x979.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-3-600x765.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-6.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img decoding=\"async\" width=\"600\" height=\"792\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-6.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-6.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-6-227x300.jpg 227w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-7.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"792\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-7.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-7.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-7-227x300.jpg 227w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-8.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"792\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-8.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-8.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-8-227x300.jpg 227w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-9.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"792\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-9.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-9.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-9-227x300.jpg 227w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-10.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"792\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-10.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-10.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-10-227x300.jpg 227w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-11.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"792\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-11.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-11.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-11-227x300.jpg 227w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header.jpg 1920w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header-300x169.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header-1024x576.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header-768x432.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header-1536x864.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-new-header-600x338.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-5.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-5.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-5-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-26.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1088\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-26.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-26.jpg 900w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-26-248x300.jpg 248w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-26-847x1024.jpg 847w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-26-768x928.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-26-600x725.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-27.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-27.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-27.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-27-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-3.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-3.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-3-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header.jpg 1920w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header-300x169.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header-1024x576.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header-768x432.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header-1536x864.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/chilly-room-header-600x338.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1088\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-2.jpg 900w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-2-248x300.jpg 248w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-2-847x1024.jpg 847w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-2-768x928.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-2-600x725.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-2.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/orange-room-gallery-2-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1088\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-1.jpg 900w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-1-248x300.jpg 248w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-1-847x1024.jpg 847w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-1-768x928.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-1-600x725.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-3.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-3.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-3-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-2.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-gallery-2-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header.jpg 1920w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header-300x169.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header-1024x576.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header-768x432.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header-1536x864.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-header-600x338.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-gallery-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-gallery-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-gallery-1.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/red-room-gallery-1-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-gallery-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-gallery-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-gallery-1.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/green-room-gallery-1-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-486\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"1088\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-2.jpg 900w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-2-248x300.jpg 248w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-2-847x1024.jpg 847w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-2-768x928.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-2-600x725.jpg 600w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d114be elementor-widget__width-inherit elementor-widget elementor-widget-oysha_core_section_title\" data-id=\"5d114be\" data-element_type=\"widget\" data-widget_type=\"oysha_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--center  \">\n\t\t<h3 class=\"qodef-m-title\" >\n\t\t\t\t\t\u0397 \u03ba\u03b1\u03c1\u03b4\u03b9\u03ac \u03c4\u03bf\u03c5 \u03c3\u03c0\u03b9\u03c4\u03b9\u03bf\u03cd\t\t\t<\/h3>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-943842d elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"943842d\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--3 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1300\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49-300x300.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49-1024x1024.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49-150x150.jpg 150w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49-768x768.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49-650x650.jpg 650w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49-600x600.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-49-100x100.jpg 100w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1300\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50-300x300.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50-1024x1024.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50-150x150.jpg 150w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50-768x768.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50-650x650.jpg 650w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50-600x600.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-50-100x100.jpg 100w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-18.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"766\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-18.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-18.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-18-300x177.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-18-1024x603.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-18-768x453.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-18-600x354.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"959\" height=\"959\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us.jpg 959w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us-300x300.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us-150x150.jpg 150w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us-768x768.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us-650x650.jpg 650w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us-600x600.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-book-now-about-us-100x100.jpg 100w\" sizes=\"(max-width: 959px) 100vw, 959px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1.jpg 1920w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1-300x169.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1-1024x576.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1-768x432.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1-1536x864.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-1-1-600x338.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-16.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1040\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-16.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-16.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-16-300x240.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-16-1024x819.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-16-768x614.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-16-600x480.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-65.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-65.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-65.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-65-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1300\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52-300x300.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52-1024x1024.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52-150x150.jpg 150w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52-768x768.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52-650x650.jpg 650w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52-600x600.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-52-100x100.jpg 100w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-63.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-63.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-63.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-63-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-54.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1020\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-54.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-54.jpg 800w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-54-235x300.jpg 235w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-54-768x979.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-54-600x765.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-67.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-67.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-67.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-67-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-66.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-66.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-66.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-66-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1300\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51-300x300.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51-1024x1024.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51-150x150.jpg 150w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51-768x768.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51-650x650.jpg 650w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51-600x600.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-51-100x100.jpg 100w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32.jpg\" data-type=\"image\" data-fslightbox=\"gallery-154\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1300\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32-300x300.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32-1024x1024.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32-150x150.jpg 150w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32-768x768.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32-650x650.jpg 650w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32-600x600.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-32-100x100.jpg 100w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a46b421 elementor-widget__width-inherit elementor-widget elementor-widget-oysha_core_section_title\" data-id=\"a46b421\" data-element_type=\"widget\" data-widget_type=\"oysha_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--center  \">\n\t\t<h3 class=\"qodef-m-title\" >\n\t\t\t\t\t\u03a0\u03c1\u03c9\u03b9\u03bd\u03ad\u03c2 \u03c3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03b6\u03b5\u03c3\u03c4\u03b1\u03c3\u03b9\u03ac\u03c2\t\t\t<\/h3>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9ca76c elementor-widget elementor-widget-qi_addons_for_elementor_image_gallery_pinterest\" data-id=\"e9ca76c\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_image_gallery_pinterest.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m qodef-qi-image-gallery-pinterest qodef-qi-fslightbox-popup qodef-popup-gallery qodef-image--hover-zoom qodef-qi-grid qodef-layout--qi-masonry qodef-col-num--3 qodef-responsive--predefined\">\n\t<div class=\"qodef-grid-inner\">\n\t\t\t<div class=\"qodef-qi-grid-masonry-sizer\"><\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1879\" height=\"966\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2.jpg 1879w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2-300x154.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2-1024x526.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2-768x395.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2-1536x790.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-2-600x308.jpg 600w\" sizes=\"(max-width: 1879px) 100vw, 1879px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-5.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"968\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-5.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-5.jpg 800w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-5-248x300.jpg 248w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-5-768x929.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-5-600x726.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-21.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"766\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-21.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-21.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-21-300x177.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-21-1024x603.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-21-768x453.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-21-600x354.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo.jpg 1920w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo-300x169.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo-1024x576.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo-768x432.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo-1536x864.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/blue-room-header-photo-600x338.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-17.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"766\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-17.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-17.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-17-300x177.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-17-1024x603.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-17-768x453.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-17-600x354.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-64.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"739\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-64.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-64.jpg 600w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/09\/colours-chalet-64-244x300.jpg 244w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"730\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14.jpg 1920w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14-300x114.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14-1024x389.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14-768x292.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14-1536x584.jpg 1536w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-14-600x228.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-20.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"766\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-20.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-20.jpg 1300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-20-300x177.jpg 300w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-20-1024x603.jpg 1024w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-20-768x453.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/colours-chalet-20-600x354.jpg 600w\" sizes=\"(max-width: 1300px) 100vw, 1300px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-6.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"202\" height=\"281\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-agrotoyrism-6.jpg\" class=\"attachment-full size-full\" alt=\"\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item\">\n\t<div class=\"qodef-e-inner\">\n\t\t\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-about-us-2.jpg\" data-type=\"image\" data-fslightbox=\"gallery-163\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"968\" src=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-about-us-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-about-us-2.jpg 800w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-about-us-2-248x300.jpg 248w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-about-us-2-768x929.jpg 768w, https:\/\/colourschalet.gr\/wp-content\/uploads\/2025\/08\/Colours-chalet-about-us-2-600x726.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t<\/a>\n\t\t\t<\/div>\n<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u03a3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03c0\u03bf\u03c5 \u03bc\u03b9\u03bb\u03bf\u03cd\u03bd \u03b1\u03c0\u03cc \u03bc\u03cc\u03bd\u03b5\u03c2 \u03c4\u03bf\u03c5\u03c2 \u03a3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03c0\u03bf\u03c5 \u03bc\u03b9\u03bb\u03bf\u03cd\u03bd \u03b1\u03c0\u03cc \u03bc\u03cc\u03bd\u03b5\u03c2 \u03c4\u03bf\u03c5\u03c2 \u0388\u03be\u03b9 \u03b1\u03c0\u03bf\u03c7\u03c1\u03ce\u03c3\u03b5\u03b9\u03c2 \u03ac\u03bd\u03b5\u03c3\u03b7\u03c2 \u0397 \u03ba\u03b1\u03c1\u03b4\u03b9\u03ac \u03c4\u03bf\u03c5 \u03c3\u03c0\u03b9\u03c4\u03b9\u03bf\u03cd \u03a0\u03c1\u03c9\u03b9\u03bd\u03ad\u03c2 \u03c3\u03c4\u03b9\u03b3\u03bc\u03ad\u03c2 \u03b6\u03b5\u03c3\u03c4\u03b1\u03c3\u03b9\u03ac\u03c2<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-4604","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/pages\/4604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/comments?post=4604"}],"version-history":[{"count":7,"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/pages\/4604\/revisions"}],"predecessor-version":[{"id":4962,"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/pages\/4604\/revisions\/4962"}],"wp:attachment":[{"href":"https:\/\/colourschalet.gr\/el\/wp-json\/wp\/v2\/media?parent=4604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}